{"id":188330,"date":"2014-02-20T00:00:00","date_gmt":"2014-02-19T23:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/persbericht-van-test-aankoop\/"},"modified":"2026-08-27T15:11:31","modified_gmt":"2026-08-27T13:11:31","slug":"persbericht-van-test-aankoop","status":"publish","type":"post","link":"https:\/\/a.cbip.be\/nl\/persbericht-van-test-aankoop\/","title":{"rendered":"Persbericht van Test- Aankoop"},"content":{"rendered":"<div class='tekst'>\n<p>Test-Aankoop geeft in een persbericht 573 geneesmiddelen een slecht rapport en stelt dat voor 113 ervan het gebruik af te raden is. Deze boodschap lokte heel wat reactie uit.<\/p>\n<p>Er zijn gelukkig de laatste jaren in Belgi\u00eb initiatieven genomen om tal van obsolete geneesmiddelen uit de markt te halen. Toch zijn er nog steeds een aantal geneesmiddelen beschikbaar waarvoor er een gebrek is aan wetenschappelijke ondersteuning van hun doeltreffendheid of waar de doeltreffendheid niet opweegt tegen de risico\u2019s.<\/p>\n<p>Ook het BCFI is van oordeel dat een aantal geneesmiddelen geen plaats meer hebben; dit wordt in het Repertorium expliciet vermeld of aangeduid met een negatief posologie-advies (\u201cPosol \u2013\u201c).<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Test-Aankoop geeft in een persbericht 573 geneesmiddelen een slecht rapport  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43,184],"tags":[20213,20224],"class_list":["post-188330","post","type-post","status-publish","format-standard","hentry","category-nieuw","category-2014-nl","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/a.cbip.be\/nl\/wp-json\/wp\/v2\/posts\/188330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a.cbip.be\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/a.cbip.be\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/a.cbip.be\/nl\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/a.cbip.be\/nl\/wp-json\/wp\/v2\/comments?post=188330"}],"version-history":[{"count":1,"href":"https:\/\/a.cbip.be\/nl\/wp-json\/wp\/v2\/posts\/188330\/revisions"}],"predecessor-version":[{"id":190885,"href":"https:\/\/a.cbip.be\/nl\/wp-json\/wp\/v2\/posts\/188330\/revisions\/190885"}],"wp:attachment":[{"href":"https:\/\/a.cbip.be\/nl\/wp-json\/wp\/v2\/media?parent=188330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/a.cbip.be\/nl\/wp-json\/wp\/v2\/categories?post=188330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/a.cbip.be\/nl\/wp-json\/wp\/v2\/tags?post=188330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}